{"id":8461,"date":"2019-05-21T17:45:07","date_gmt":"2019-05-21T15:45:07","guid":{"rendered":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350.jpg"},"modified":"2019-05-21T17:45:07","modified_gmt":"2019-05-21T15:45:07","slug":"retro-tiseurs-rassemblement-2019-350","status":"inherit","type":"attachment","link":"https:\/\/retro-tiseurs.com\/wp-retro\/retro-tiseurs-rassemblement-2019-350\/","title":{"rendered":"R\u00e9tro-Tiseurs Rassemblement 2019-350"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-8461","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350-300x200.jpg 300w, https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350-1024x681.jpg 1024w, https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350-1200x798.jpg 1200w, https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350-272x182.jpg 272w, https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350.jpg 1800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1800,"height":1197,"file":"2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350.jpg","sizes":{"thumbnail":{"file":"R\u00e9tro-Tiseurs-Rassemblement-2019-350-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350-150x150.jpg"},"medium":{"file":"R\u00e9tro-Tiseurs-Rassemblement-2019-350-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350-300x200.jpg"},"large":{"file":"R\u00e9tro-Tiseurs-Rassemblement-2019-350-1024x681.jpg","width":1024,"height":681,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350-1024x681.jpg"},"post-thumbnail":{"file":"R\u00e9tro-Tiseurs-Rassemblement-2019-350-1200x798.jpg","width":1200,"height":798,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350-1200x798.jpg"},"sow-carousel-default":{"file":"R\u00e9tro-Tiseurs-Rassemblement-2019-350-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350-272x182.jpg"},"full":{"file":"R\u00e9tro-Tiseurs-Rassemblement-2019-350.jpg","width":1800,"height":1197,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350.jpg"}},"image_meta":{"aperture":"5","credit":"","camera":"NIKON D3200","caption":"","created_timestamp":"1558290076","copyright":"","focal_length":"18","iso":"100","shutter_speed":"0.005","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-350.jpg","_links":{"self":[{"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/media\/8461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/comments?post=8461"}]}}