{"id":8168,"date":"2019-05-21T17:25:15","date_gmt":"2019-05-21T15:25:15","guid":{"rendered":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057.jpg"},"modified":"2019-05-21T17:25:15","modified_gmt":"2019-05-21T15:25:15","slug":"retro-tiseurs-rassemblement-2019-057","status":"inherit","type":"attachment","link":"https:\/\/retro-tiseurs.com\/wp-retro\/retro-tiseurs-rassemblement-2019-057\/","title":{"rendered":"R\u00e9tro-Tiseurs Rassemblement 2019-057"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-8168","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057-300x225.jpg 300w, https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057-1024x768.jpg 1024w, https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057-1200x900.jpg 1200w, https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057.jpg 1800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1800,"height":1350,"file":"2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057.jpg","sizes":{"thumbnail":{"file":"R\u00e9tro-Tiseurs-Rassemblement-2019-057-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057-150x150.jpg"},"medium":{"file":"R\u00e9tro-Tiseurs-Rassemblement-2019-057-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057-300x225.jpg"},"large":{"file":"R\u00e9tro-Tiseurs-Rassemblement-2019-057-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057-1024x768.jpg"},"post-thumbnail":{"file":"R\u00e9tro-Tiseurs-Rassemblement-2019-057-1200x900.jpg","width":1200,"height":900,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057-1200x900.jpg"},"sow-carousel-default":{"file":"R\u00e9tro-Tiseurs-Rassemblement-2019-057-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057-272x182.jpg"},"full":{"file":"R\u00e9tro-Tiseurs-Rassemblement-2019-057.jpg","width":1800,"height":1350,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057.jpg"}},"image_meta":{"aperture":"4","credit":"","camera":"X20","caption":"","created_timestamp":"1558266517","copyright":"","focal_length":"7.1","iso":"400","shutter_speed":"0.0011764705882353","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2019\/05\/R\u00e9tro-Tiseurs-Rassemblement-2019-057.jpg","_links":{"self":[{"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/media\/8168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/comments?post=8168"}]}}