{"id":6469,"date":"2018-01-08T17:49:20","date_gmt":"2018-01-08T16:49:20","guid":{"rendered":"http:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125.jpg"},"modified":"2018-01-08T17:49:20","modified_gmt":"2018-01-08T16:49:20","slug":"retro-tiseurs-2017-12-31-reveillon-125","status":"inherit","type":"attachment","link":"https:\/\/retro-tiseurs.com\/wp-retro\/retro-tiseurs-2017-12-31-reveillon-125\/","title":{"rendered":"R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon (125)"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-6469","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125-300x200.jpg 300w, https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125-1024x681.jpg 1024w, https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125-1200x798.jpg 1200w, https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125.jpg 1600w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1064,"file":"2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125.jpg","sizes":{"thumbnail":{"file":"R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125-150x150.jpg"},"medium":{"file":"R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125-300x200.jpg"},"large":{"file":"R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125-1024x681.jpg","width":1024,"height":681,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125-1024x681.jpg"},"post-thumbnail":{"file":"R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125-1200x798.jpg","width":1200,"height":798,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125-1200x798.jpg"},"full":{"file":"R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125.jpg","width":1600,"height":1064,"mime_type":"image\/jpeg","source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125.jpg"}},"image_meta":{"aperture":"3.5","credit":"","camera":"NIKON D3200","caption":"","created_timestamp":"1514765669","copyright":"","focal_length":"18","iso":"1600","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-content\/uploads\/2018\/01\/R\u00e9tro-Tiseurs-2017-12-31-R\u00e9veillon-125.jpg","_links":{"self":[{"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/media\/6469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/retro-tiseurs.com\/wp-retro\/wp-json\/wp\/v2\/comments?post=6469"}]}}